{"id":1650,"date":"2025-06-18T15:00:12","date_gmt":"2025-06-18T18:00:12","guid":{"rendered":"https:\/\/www.massafmedical.com.br\/loja\/?post_type=product&#038;p=1650"},"modified":"2025-11-04T17:25:04","modified_gmt":"2025-11-04T20:25:04","slug":"garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2","status":"publish","type":"product","link":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/","title":{"rendered":"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS &#8211; COM v\u00e1lvula CO2"},"content":{"rendered":"<table class=\"b-t-1 table table-view borderless info-table font-semi-small info-display-with-divider light-info-table infos-widget-table\" style=\"font-size: 1rem;\">\n<tbody>\n<tr>\n<td class=\"info-display-divider\">\n<div class=\"data-edit v-overflow-hidden height-max text-break-word full-width\">\n<p>Garrafa de \u00e1gua para sistemas de endoscopia da marca Olympus para linha 140\/145\/150\/160\/170\/180\/190 original.<\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>A garrafa de \u00e1gua \u00e9 um componente essencial dos sistemas de irriga\u00e7\u00e3o utilizados durante procedimentos endosc\u00f3picos, como a endoscopia digestiva alta (gastroscopia) e a colonoscopia. Ela \u00e9 conhecida como &#8220;garrafa de \u00e1gua&#8221; porque geralmente cont\u00e9m \u00e1gua ou solu\u00e7\u00e3o de irriga\u00e7\u00e3o.<\/p>\n<p>REF: 0000007960499<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A garrafa \u00e9 conectada ao sistema de irriga\u00e7\u00e3o do endosc\u00f3pio e fornece fluido que \u00e9 usado para limpeza e lavagem durante o procedimento.<\/p>\n","protected":false},"featured_media":1651,"template":"","meta":[],"product_brand":[],"product_cat":[91,51],"product_tag":[],"class_list":{"0":"post-1650","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-acessorios-endoscopia","7":"product_cat-produtos-hospitalares-e-para-pacientes","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS - COM v\u00e1lvula CO2 - Massaf Medical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS - COM v\u00e1lvula CO2 - Massaf Medical\" \/>\n<meta property=\"og:description\" content=\"A garrafa \u00e9 conectada ao sistema de irriga\u00e7\u00e3o do endosc\u00f3pio e fornece fluido que \u00e9 usado para limpeza e lavagem durante o procedimento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/\" \/>\n<meta property=\"og:site_name\" content=\"Massaf Medical\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/MASSAFMEDICAL\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T20:25:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/\",\"url\":\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/\",\"name\":\"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS - COM v\u00e1lvula CO2 - Massaf Medical\",\"isPartOf\":{\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg\",\"datePublished\":\"2025-06-18T18:00:12+00:00\",\"dateModified\":\"2025-11-04T20:25:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#primaryimage\",\"url\":\"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg\",\"contentUrl\":\"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.massafmedical.com.br\/loja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/www.massafmedical.com.br\/loja\/nossos-produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS &#8211; COM v\u00e1lvula CO2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/#website\",\"url\":\"https:\/\/www.massafmedical.com.br\/loja\/\",\"name\":\"Massaf Medical\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.massafmedical.com.br\/loja\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/#organization\",\"name\":\"Massaf Medical\",\"url\":\"https:\/\/www.massafmedical.com.br\/loja\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2020\/10\/logotipo-big.png\",\"contentUrl\":\"http:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2020\/10\/logotipo-big.png\",\"width\":750,\"height\":253,\"caption\":\"Massaf Medical\"},\"image\":{\"@id\":\"https:\/\/www.massafmedical.com.br\/loja\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/MASSAFMEDICAL\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS - COM v\u00e1lvula CO2 - Massaf Medical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/","og_locale":"pt_BR","og_type":"article","og_title":"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS - COM v\u00e1lvula CO2 - Massaf Medical","og_description":"A garrafa \u00e9 conectada ao sistema de irriga\u00e7\u00e3o do endosc\u00f3pio e fornece fluido que \u00e9 usado para limpeza e lavagem durante o procedimento.","og_url":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/","og_site_name":"Massaf Medical","article_publisher":"http:\/\/www.facebook.com\/MASSAFMEDICAL","article_modified_time":"2025-11-04T20:25:04+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/","url":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/","name":"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS - COM v\u00e1lvula CO2 - Massaf Medical","isPartOf":{"@id":"https:\/\/www.massafmedical.com.br\/loja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#primaryimage"},"image":{"@id":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg","datePublished":"2025-06-18T18:00:12+00:00","dateModified":"2025-11-04T20:25:04+00:00","breadcrumb":{"@id":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#primaryimage","url":"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg","contentUrl":"https:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-14.38.19.jpeg","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.massafmedical.com.br\/loja\/produto\/garrafa-de-agua-olympus-140-190-maj-901-argus-com-valvula-co2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.massafmedical.com.br\/loja\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.massafmedical.com.br\/loja\/nossos-produtos\/"},{"@type":"ListItem","position":3,"name":"Garrafa de \u00c1gua OLYMPUS 140\/190 MAJ-901\/ ARGUS &#8211; COM v\u00e1lvula CO2"}]},{"@type":"WebSite","@id":"https:\/\/www.massafmedical.com.br\/loja\/#website","url":"https:\/\/www.massafmedical.com.br\/loja\/","name":"Massaf Medical","description":"","publisher":{"@id":"https:\/\/www.massafmedical.com.br\/loja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.massafmedical.com.br\/loja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.massafmedical.com.br\/loja\/#organization","name":"Massaf Medical","url":"https:\/\/www.massafmedical.com.br\/loja\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.massafmedical.com.br\/loja\/#\/schema\/logo\/image\/","url":"http:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2020\/10\/logotipo-big.png","contentUrl":"http:\/\/www.massafmedical.com.br\/loja\/wp-content\/uploads\/2020\/10\/logotipo-big.png","width":750,"height":253,"caption":"Massaf Medical"},"image":{"@id":"https:\/\/www.massafmedical.com.br\/loja\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/MASSAFMEDICAL"]}]}},"_links":{"self":[{"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/product\/1650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/media\/1651"}],"wp:attachment":[{"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/media?parent=1650"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/product_brand?post=1650"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=1650"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.massafmedical.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=1650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}